{"id":13869,"date":"2021-09-18T14:58:00","date_gmt":"2021-09-18T13:58:00","guid":{"rendered":"https:\/\/sebastianodessanay.com\/?p=13869"},"modified":"2021-09-28T15:08:13","modified_gmt":"2021-09-28T14:08:13","slug":"the-lost-spells-rd","status":"publish","type":"post","link":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/","title":{"rendered":"The Lost Spells R&#038;D"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost_spells.jpg\" alt=\"\" class=\"wp-image-13870\" srcset=\"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost_spells.jpg 1024w, https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost_spells-980x980.jpg 980w, https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost_spells-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dal 20 al 27 settembre lavorer\u00f2 alla fase di R&amp;D (research and development) del musical <strong>The Lost Spells<\/strong>, basato sul bellissimo libro illustrato con testi di <strong>Robert Macfarlane<\/strong> e illustrazioni di <strong>Jackie Morris<\/strong>, portato avanti dalla compagnia teatrale <a href=\"https:\/\/goblintheatre.co.uk\/\" target=\"_blank\" rel=\"noreferrer noopener\">Goblin Theatre<\/a> al <a href=\"https:\/\/watfordpalacetheatre.co.uk\/\" target=\"_blank\" rel=\"noreferrer noopener\">Watford Palace Theatre<\/a>. Ulteriori sviluppi sul progetto nel 2022. Stay tuned!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"841\" src=\"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost-Spell-crew-1024x841.jpeg\" alt=\"\" class=\"wp-image-13871\" srcset=\"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost-Spell-crew-1024x841.jpeg 1024w, https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost-Spell-crew-980x805.jpeg 980w, https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost-Spell-crew-480x394.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><figcaption>The Lost Spells crew at Watford Palace Theatre<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dal 20 al 27 settembre lavorer\u00f2 alla fase di R&amp;D (research and development) del musical The Lost Spells, basato sul bellissimo libro illustrato con testi di Robert Macfarlane e illustrazioni di Jackie Morris, portato avanti dalla compagnia teatrale Goblin Theatre al Watford Palace Theatre. Ulteriori sviluppi sul progetto nel 2022. Stay tuned!<\/p>\n","protected":false},"author":3,"featured_media":13870,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[5],"tags":[826,824,830,822,820,828],"class_list":["post-13869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-goblin-theatre","tag-jackie-morris","tag-musical","tag-robert-macfarlane","tag-the-lost-spells","tag-watford-palace-theatre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sebastiano Dessanay - The Lost Spells R&amp;D<\/title>\n<meta name=\"description\" content=\"Dal 20 al 27 settembre lavorer\u00f2 alla fase di R&amp;D (research and development) del musical The Lost Spells, basato sul bellissimo libro illustrato con testi di Robert Macfarlane e illustrazioni di Jackie Morris, portato avanti dalla compagnia teatrale Goblin Theatre al Watford Palace Theatre. Ulteriori sviluppi sul progetto nel 2022. Stay tuned!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sebastiano Dessanay - The Lost Spells R&amp;D\" \/>\n<meta property=\"og:description\" content=\"Dal 20 al 27 settembre lavorer\u00f2 alla fase di R&amp;D (research and development) del musical The Lost Spells, basato sul bellissimo libro illustrato con testi di Robert Macfarlane e illustrazioni di Jackie Morris, portato avanti dalla compagnia teatrale Goblin Theatre al Watford Palace Theatre. Ulteriori sviluppi sul progetto nel 2022. Stay tuned!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/\" \/>\n<meta property=\"og:site_name\" content=\"Sebastiano Dessanay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sebdessanaymusic\/?ref=bookmarks\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-18T13:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-28T14:08:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost_spells.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Dessanay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sebdessanay\" \/>\n<meta name=\"twitter:site\" content=\"@sebdessanay\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Dessanay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/\"},\"author\":{\"name\":\"Sebastiano Dessanay\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/#\\\/schema\\\/person\\\/862266eb9e7326a003256dd4e7884f1d\"},\"headline\":\"The Lost Spells R&#038;D\",\"datePublished\":\"2021-09-18T13:58:00+00:00\",\"dateModified\":\"2021-09-28T14:08:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/\"},\"wordCount\":64,\"image\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sebastianodessanay.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Lost_spells.jpg\",\"keywords\":[\"goblin theatre\",\"jackie morris\",\"musical\",\"robert macfarlane\",\"the lost spells\",\"watford palace theatre\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/\",\"url\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/\",\"name\":\"Sebastiano Dessanay - The Lost Spells R&D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sebastianodessanay.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Lost_spells.jpg\",\"datePublished\":\"2021-09-18T13:58:00+00:00\",\"dateModified\":\"2021-09-28T14:08:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/#\\\/schema\\\/person\\\/862266eb9e7326a003256dd4e7884f1d\"},\"description\":\"Dal 20 al 27 settembre lavorer\u00f2 alla fase di R&D (research and development) del musical The Lost Spells, basato sul bellissimo libro illustrato con testi di Robert Macfarlane e illustrazioni di Jackie Morris, portato avanti dalla compagnia teatrale Goblin Theatre al Watford Palace Theatre. Ulteriori sviluppi sul progetto nel 2022. Stay tuned!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sebastianodessanay.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Lost_spells.jpg\",\"contentUrl\":\"https:\\\/\\\/sebastianodessanay.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Lost_spells.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"Lost_spells\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2021\\\/09\\\/the-lost-spells-rd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Lost Spells R&#038;D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/\",\"name\":\"Sebastiano Dessanay\",\"description\":\"Compositore, Contrabbassista, Didatta\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/#\\\/schema\\\/person\\\/862266eb9e7326a003256dd4e7884f1d\",\"name\":\"Sebastiano Dessanay\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35809506356ebdd0aa292f8ff05d38c4c5c8c6cc8bea771119da6c0e9fd32818?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35809506356ebdd0aa292f8ff05d38c4c5c8c6cc8bea771119da6c0e9fd32818?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35809506356ebdd0aa292f8ff05d38c4c5c8c6cc8bea771119da6c0e9fd32818?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Dessanay\"},\"sameAs\":[\"https:\\\/\\\/sebastianodessanay.com\\\/\"],\"url\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/author\\\/seb-dessanay\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sebastiano Dessanay - The Lost Spells R&D","description":"Dal 20 al 27 settembre lavorer\u00f2 alla fase di R&D (research and development) del musical The Lost Spells, basato sul bellissimo libro illustrato con testi di Robert Macfarlane e illustrazioni di Jackie Morris, portato avanti dalla compagnia teatrale Goblin Theatre al Watford Palace Theatre. Ulteriori sviluppi sul progetto nel 2022. Stay tuned!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/","og_locale":"it_IT","og_type":"article","og_title":"Sebastiano Dessanay - The Lost Spells R&D","og_description":"Dal 20 al 27 settembre lavorer\u00f2 alla fase di R&D (research and development) del musical The Lost Spells, basato sul bellissimo libro illustrato con testi di Robert Macfarlane e illustrazioni di Jackie Morris, portato avanti dalla compagnia teatrale Goblin Theatre al Watford Palace Theatre. Ulteriori sviluppi sul progetto nel 2022. Stay tuned!","og_url":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/","og_site_name":"Sebastiano Dessanay","article_publisher":"https:\/\/www.facebook.com\/sebdessanaymusic\/?ref=bookmarks","article_published_time":"2021-09-18T13:58:00+00:00","article_modified_time":"2021-09-28T14:08:13+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost_spells.jpg","type":"image\/jpeg"}],"author":"Sebastiano Dessanay","twitter_card":"summary_large_image","twitter_creator":"@sebdessanay","twitter_site":"@sebdessanay","twitter_misc":{"Scritto da":"Sebastiano Dessanay","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/#article","isPartOf":{"@id":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/"},"author":{"name":"Sebastiano Dessanay","@id":"https:\/\/sebastianodessanay.com\/it\/#\/schema\/person\/862266eb9e7326a003256dd4e7884f1d"},"headline":"The Lost Spells R&#038;D","datePublished":"2021-09-18T13:58:00+00:00","dateModified":"2021-09-28T14:08:13+00:00","mainEntityOfPage":{"@id":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/"},"wordCount":64,"image":{"@id":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/#primaryimage"},"thumbnailUrl":"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost_spells.jpg","keywords":["goblin theatre","jackie morris","musical","robert macfarlane","the lost spells","watford palace theatre"],"articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/","url":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/","name":"Sebastiano Dessanay - The Lost Spells R&D","isPartOf":{"@id":"https:\/\/sebastianodessanay.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/#primaryimage"},"image":{"@id":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/#primaryimage"},"thumbnailUrl":"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost_spells.jpg","datePublished":"2021-09-18T13:58:00+00:00","dateModified":"2021-09-28T14:08:13+00:00","author":{"@id":"https:\/\/sebastianodessanay.com\/it\/#\/schema\/person\/862266eb9e7326a003256dd4e7884f1d"},"description":"Dal 20 al 27 settembre lavorer\u00f2 alla fase di R&D (research and development) del musical The Lost Spells, basato sul bellissimo libro illustrato con testi di Robert Macfarlane e illustrazioni di Jackie Morris, portato avanti dalla compagnia teatrale Goblin Theatre al Watford Palace Theatre. Ulteriori sviluppi sul progetto nel 2022. Stay tuned!","breadcrumb":{"@id":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/#primaryimage","url":"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost_spells.jpg","contentUrl":"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2021\/09\/Lost_spells.jpg","width":1024,"height":1024,"caption":"Lost_spells"},{"@type":"BreadcrumbList","@id":"https:\/\/sebastianodessanay.com\/it\/2021\/09\/the-lost-spells-rd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sebastianodessanay.com\/it\/"},{"@type":"ListItem","position":2,"name":"The Lost Spells R&#038;D"}]},{"@type":"WebSite","@id":"https:\/\/sebastianodessanay.com\/it\/#website","url":"https:\/\/sebastianodessanay.com\/it\/","name":"Sebastiano Dessanay","description":"Compositore, Contrabbassista, Didatta","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sebastianodessanay.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/sebastianodessanay.com\/it\/#\/schema\/person\/862266eb9e7326a003256dd4e7884f1d","name":"Sebastiano Dessanay","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35809506356ebdd0aa292f8ff05d38c4c5c8c6cc8bea771119da6c0e9fd32818?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35809506356ebdd0aa292f8ff05d38c4c5c8c6cc8bea771119da6c0e9fd32818?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35809506356ebdd0aa292f8ff05d38c4c5c8c6cc8bea771119da6c0e9fd32818?s=96&d=mm&r=g","caption":"Sebastiano Dessanay"},"sameAs":["https:\/\/sebastianodessanay.com\/"],"url":"https:\/\/sebastianodessanay.com\/it\/author\/seb-dessanay\/"}]}},"_links":{"self":[{"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/posts\/13869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/comments?post=13869"}],"version-history":[{"count":1,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/posts\/13869\/revisions"}],"predecessor-version":[{"id":13872,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/posts\/13869\/revisions\/13872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/media\/13870"}],"wp:attachment":[{"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/media?parent=13869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/categories?post=13869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/tags?post=13869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}