{"id":8985,"date":"2018-06-13T20:18:54","date_gmt":"2018-06-13T18:18:54","guid":{"rendered":"https:\/\/sebastianodessanay.com\/?p=8985"},"modified":"2026-01-07T22:30:06","modified_gmt":"2026-01-07T21:30:06","slug":"dunmall-mwamba-dessanay-bashford-al-vortex","status":"publish","type":"post","link":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/","title":{"rendered":"Dunmall, Mwamba, Dessanay, Bashford al Vortex"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"302\" src=\"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2018\/06\/corey-mwamba.jpeg\" alt=\"corey-mwamba\" class=\"wp-image-16866\" style=\"aspect-ratio:1.9073317121125886;width:823px;height:auto\" srcset=\"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2018\/06\/corey-mwamba.jpeg 576w, https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2018\/06\/corey-mwamba-480x252.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 576px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Gioved\u00ec 14 giugno avr\u00f2 l&#8217;onore e il piacere di suonare al leggendario <a href=\"http:\/\/www.vortexjazz.co.uk\/\">Vortex<\/a> <strong>Jazz Club di Londra<\/strong> con dei musicisti incredibili, <strong>Paul Dunmall,<\/strong> <strong>Corey Mwamba<\/strong> e<strong> James Bashford<\/strong>. Presenteremo un programma di improvvisazione radicale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il concerto inizia all ore 20. Ingresso \u00a312.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maggiori dettagli dal sito del <a href=\"http:\/\/www.vortexjazz.co.uk\/event\/paul-dunmall-corey-mwamba-sebastian-dessanay-jim-bashford\/\">Vortex<\/a>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Questa \u00e8 la prima volta che questo gruppo si esibisce insieme come quartetto. Paul Dunmall \u00e8 da molti anni una figura di primo piano al sassofono e negli ultimi quarant\u2019anni ha suonato con innumerevoli musicisti provenienti da diversi ambiti musicali. Molte delle sue registrazioni hanno ricevuto ampi consensi a livello mondiale ed \u00e8 noto per gli elevati standard della sua improvvisazione. Paul \u00e8 affiancato da tre grandi improvvisatori. Jim Bashford e Sebastian Dessanay, entrambi di base a Birmingham, hanno suonato molte volte con Paul e lo scorso anno hanno registrato due CD in formazione di trio e quartetto. Paul ha suonato diverse volte negli ultimi anni con Corey, originario di Derby, e ritiene che questo nuovo quartetto ha molte nuove aree musicali da esplorare&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torno al leggendario Vortex Jazz Club di Londra con dei musicisti incredibili: Paul Dunmall, Corey Mwamba e James Bashford.<\/p>\n","protected":false},"author":2,"featured_media":9157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1130,220,5],"tags":[1815,1818,1816,1069,1653,1814,1817],"class_list":["post-8985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-it","category-live-it","category-notizie","tag-corey-mwamba","tag-improvisation","tag-james-bashford","tag-jazz-it","tag-londra","tag-paul-dunmall","tag-vortex"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dunmall, Mwamba, Dessanay, Bashford al Vortex<\/title>\n<meta name=\"description\" content=\"Avr\u00f2 l&#039;onore e il piacere di suonare al leggendario Vortex Jazz Club di Londra con dei musicisti incredibili\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dunmall, Mwamba, Dessanay, Bashford al Vortex\" \/>\n<meta property=\"og:description\" content=\"Avr\u00f2 l&#039;onore e il piacere di suonare al leggendario Vortex Jazz Club di Londra con dei musicisti incredibili\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/\" \/>\n<meta property=\"og:site_name\" content=\"Sebastiano Dessanay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sebdessanaymusic\/?ref=bookmarks\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-13T18:18:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-07T21:30:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2018\/06\/Vortex-jazz-Dunmall-Dessanay-Mwamba-Bashford.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"784\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sd.sebastiano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sebdessanay\" \/>\n<meta name=\"twitter:site\" content=\"@sebdessanay\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sd.sebastiano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/\"},\"author\":{\"name\":\"sd.sebastiano\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/#\\\/schema\\\/person\\\/341ed94c5c16fbe00c1fce6aa1cb28f8\"},\"headline\":\"Dunmall, Mwamba, Dessanay, Bashford al Vortex\",\"datePublished\":\"2018-06-13T18:18:54+00:00\",\"dateModified\":\"2026-01-07T21:30:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/\"},\"wordCount\":173,\"image\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sebastianodessanay.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Vortex-jazz-Dunmall-Dessanay-Mwamba-Bashford.jpg\",\"keywords\":[\"corey mwamba\",\"improvisation\",\"james bashford\",\"jazz\",\"londra\",\"paul dunmall\",\"vortex\"],\"articleSection\":[\"Eventi\",\"Live\",\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/\",\"url\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/\",\"name\":\"Dunmall, Mwamba, Dessanay, Bashford al Vortex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sebastianodessanay.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Vortex-jazz-Dunmall-Dessanay-Mwamba-Bashford.jpg\",\"datePublished\":\"2018-06-13T18:18:54+00:00\",\"dateModified\":\"2026-01-07T21:30:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/#\\\/schema\\\/person\\\/341ed94c5c16fbe00c1fce6aa1cb28f8\"},\"description\":\"Avr\u00f2 l'onore e il piacere di suonare al leggendario Vortex Jazz Club di Londra con dei musicisti incredibili\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sebastianodessanay.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Vortex-jazz-Dunmall-Dessanay-Mwamba-Bashford.jpg\",\"contentUrl\":\"https:\\\/\\\/sebastianodessanay.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Vortex-jazz-Dunmall-Dessanay-Mwamba-Bashford.jpg\",\"width\":784,\"height\":441,\"caption\":\"Vortex jazz, Dunmall Dessanay Mwamba Bashford\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/2018\\\/06\\\/dunmall-mwamba-dessanay-bashford-al-vortex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dunmall, Mwamba, Dessanay, Bashford al Vortex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/\",\"name\":\"Sebastiano Dessanay\",\"description\":\"Compositore, Contrabbassista, Didatta\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/#\\\/schema\\\/person\\\/341ed94c5c16fbe00c1fce6aa1cb28f8\",\"name\":\"sd.sebastiano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"sd.sebastiano\"},\"url\":\"https:\\\/\\\/sebastianodessanay.com\\\/it\\\/author\\\/sd-sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dunmall, Mwamba, Dessanay, Bashford al Vortex","description":"Avr\u00f2 l'onore e il piacere di suonare al leggendario Vortex Jazz Club di Londra con dei musicisti incredibili","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/","og_locale":"it_IT","og_type":"article","og_title":"Dunmall, Mwamba, Dessanay, Bashford al Vortex","og_description":"Avr\u00f2 l'onore e il piacere di suonare al leggendario Vortex Jazz Club di Londra con dei musicisti incredibili","og_url":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/","og_site_name":"Sebastiano Dessanay","article_publisher":"https:\/\/www.facebook.com\/sebdessanaymusic\/?ref=bookmarks","article_published_time":"2018-06-13T18:18:54+00:00","article_modified_time":"2026-01-07T21:30:06+00:00","og_image":[{"width":784,"height":441,"url":"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2018\/06\/Vortex-jazz-Dunmall-Dessanay-Mwamba-Bashford.jpg","type":"image\/jpeg"}],"author":"sd.sebastiano","twitter_card":"summary_large_image","twitter_creator":"@sebdessanay","twitter_site":"@sebdessanay","twitter_misc":{"Scritto da":"sd.sebastiano","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/#article","isPartOf":{"@id":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/"},"author":{"name":"sd.sebastiano","@id":"https:\/\/sebastianodessanay.com\/it\/#\/schema\/person\/341ed94c5c16fbe00c1fce6aa1cb28f8"},"headline":"Dunmall, Mwamba, Dessanay, Bashford al Vortex","datePublished":"2018-06-13T18:18:54+00:00","dateModified":"2026-01-07T21:30:06+00:00","mainEntityOfPage":{"@id":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/"},"wordCount":173,"image":{"@id":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/#primaryimage"},"thumbnailUrl":"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2018\/06\/Vortex-jazz-Dunmall-Dessanay-Mwamba-Bashford.jpg","keywords":["corey mwamba","improvisation","james bashford","jazz","londra","paul dunmall","vortex"],"articleSection":["Eventi","Live","Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/","url":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/","name":"Dunmall, Mwamba, Dessanay, Bashford al Vortex","isPartOf":{"@id":"https:\/\/sebastianodessanay.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/#primaryimage"},"image":{"@id":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/#primaryimage"},"thumbnailUrl":"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2018\/06\/Vortex-jazz-Dunmall-Dessanay-Mwamba-Bashford.jpg","datePublished":"2018-06-13T18:18:54+00:00","dateModified":"2026-01-07T21:30:06+00:00","author":{"@id":"https:\/\/sebastianodessanay.com\/it\/#\/schema\/person\/341ed94c5c16fbe00c1fce6aa1cb28f8"},"description":"Avr\u00f2 l'onore e il piacere di suonare al leggendario Vortex Jazz Club di Londra con dei musicisti incredibili","breadcrumb":{"@id":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/#primaryimage","url":"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2018\/06\/Vortex-jazz-Dunmall-Dessanay-Mwamba-Bashford.jpg","contentUrl":"https:\/\/sebastianodessanay.com\/wp-content\/uploads\/2018\/06\/Vortex-jazz-Dunmall-Dessanay-Mwamba-Bashford.jpg","width":784,"height":441,"caption":"Vortex jazz, Dunmall Dessanay Mwamba Bashford"},{"@type":"BreadcrumbList","@id":"https:\/\/sebastianodessanay.com\/it\/2018\/06\/dunmall-mwamba-dessanay-bashford-al-vortex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sebastianodessanay.com\/it\/"},{"@type":"ListItem","position":2,"name":"Dunmall, Mwamba, Dessanay, Bashford al Vortex"}]},{"@type":"WebSite","@id":"https:\/\/sebastianodessanay.com\/it\/#website","url":"https:\/\/sebastianodessanay.com\/it\/","name":"Sebastiano Dessanay","description":"Compositore, Contrabbassista, Didatta","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sebastianodessanay.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/sebastianodessanay.com\/it\/#\/schema\/person\/341ed94c5c16fbe00c1fce6aa1cb28f8","name":"sd.sebastiano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"sd.sebastiano"},"url":"https:\/\/sebastianodessanay.com\/it\/author\/sd-sebastiano\/"}]}},"_links":{"self":[{"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/posts\/8985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/comments?post=8985"}],"version-history":[{"count":7,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/posts\/8985\/revisions"}],"predecessor-version":[{"id":16872,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/posts\/8985\/revisions\/16872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/media\/9157"}],"wp:attachment":[{"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/media?parent=8985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/categories?post=8985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sebastianodessanay.com\/it\/wp-json\/wp\/v2\/tags?post=8985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}